{"id":7,"count":2,"description":"Travel is the movement of people between distant geographical locations. Travel can be done by foot, bicycle, automobile, train, boat, bus, airplane, ship or other means, with or without luggage.","link":"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/category\/travel\/","name":"Travel","slug":"travel","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Travel Archives - Edger<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/category\/travel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Travel Archives - Edger\" \/>\n<meta property=\"og:description\" content=\"Travel is the movement of people between distant geographical locations. Travel can be done by foot, bicycle, automobile, train, boat, bus, airplane, ship or other means, with or without luggage.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/category\/travel\/\" \/>\n<meta property=\"og:site_name\" content=\"Edger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/category\/travel\/\",\"url\":\"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/category\/travel\/\",\"name\":\"Travel Archives - Edger\",\"isPartOf\":{\"@id\":\"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/category\/travel\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/category\/travel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Travel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/#website\",\"url\":\"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/\",\"name\":\"Edger\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Travel Archives - Edger","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/category\/travel\/","og_locale":"en_US","og_type":"article","og_title":"Travel Archives - Edger","og_description":"Travel is the movement of people between distant geographical locations. Travel can be done by foot, bicycle, automobile, train, boat, bus, airplane, ship or other means, with or without luggage.","og_url":"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/category\/travel\/","og_site_name":"Edger","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/category\/travel\/","url":"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/category\/travel\/","name":"Travel Archives - Edger","isPartOf":{"@id":"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/#website"},"breadcrumb":{"@id":"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/category\/travel\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/category\/travel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/"},{"@type":"ListItem","position":2,"name":"Travel"}]},{"@type":"WebSite","@id":"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/#website","url":"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/","name":"Edger","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/wp-json\/wp\/v2\/categories\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/themes.estudiopatagon.com\/wordpress\/edger\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}